{"id":8012,"count":3,"description":"Qualsiasi violazione di queste norme potrebbe comportare la cancellazione del bonus, perfino ove gi\u00e0 accreditato. -","link":"https:\/\/lock-smith.ae\/ar\/category\/casino-mania-login-357\/","name":"Casino Mania Login 357","slug":"casino-mania-login-357","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/lock-smith.ae\/ar\/wp-json\/wp\/v2\/categories\/8012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lock-smith.ae\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lock-smith.ae\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lock-smith.ae\/ar\/wp-json\/wp\/v2\/posts?categories=8012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}